{"id":10732,"date":"2024-12-01T15:58:42","date_gmt":"2024-12-01T15:58:42","guid":{"rendered":"https:\/\/sentiers05.fr\/?p=10732"},"modified":"2025-01-27T16:21:10","modified_gmt":"2025-01-27T16:21:10","slug":"le-rocher-de-jardanne","status":"publish","type":"post","link":"https:\/\/sentiers05.fr\/index.php\/2024\/12\/01\/le-rocher-de-jardanne\/","title":{"rendered":"Le Rocher de Jardanne"},"content":{"rendered":"\n<p>D\u00e9n.750m-Dist.11km-Dur\u00e9e:5h-Diff.2+(portion de mont\u00e9e raide)<br>6 participants<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"262\" src=\"https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_144351-584x262.jpg\" alt=\"\" class=\"wp-image-10733\" srcset=\"https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_144351-584x262.jpg 584w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_144351-300x135.jpg 300w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_144351-1536x690.jpg 1536w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_144351-2048x920.jpg 2048w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_144351-1200x539.jpg 1200w\" sizes=\"auto, (max-width: 584px) 85vw, 584px\" \/><\/figure>\n\n\n\n<p>Nous arrivons \u00e0 Serres pour 9h, accompagn\u00e9s d&rsquo;une nappe de brume givrante\u2026 Mais bien vite le soleil reprend ses marques. La mont\u00e9e commence doucement dans les ruelles de Serres jusqu&rsquo;\u00e0 la Chapelle de Bonsecour o\u00f9 une petite halte s&rsquo;impose: la vue sur la vall\u00e9e avec le voile justifie la plaque d&rsquo;orientation\u2026<\/p>\n\n\n<a class=\"wp-block-read-more\" href=\"https:\/\/sentiers05.fr\/index.php\/2024\/12\/01\/le-rocher-de-jardanne\/\" target=\"_self\">Lire la suite<span class=\"screen-reader-text\">\u00a0: Le Rocher de Jardanne<\/span><\/a>\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"262\" src=\"https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_092450-584x262.jpg\" alt=\"\" class=\"wp-image-10735\" srcset=\"https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_092450-584x262.jpg 584w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_092450-300x135.jpg 300w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_092450-1536x690.jpg 1536w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_092450-2048x920.jpg 2048w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_092450-1200x539.jpg 1200w\" sizes=\"auto, (max-width: 584px) 85vw, 584px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"262\" src=\"https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_092539-584x262.jpg\" alt=\"\" class=\"wp-image-10736\" srcset=\"https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_092539-584x262.jpg 584w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_092539-300x135.jpg 300w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_092539-1536x690.jpg 1536w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_092539-2048x920.jpg 2048w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_092539-1200x539.jpg 1200w\" sizes=\"auto, (max-width: 584px) 85vw, 584px\" \/><\/figure>\n\n\n\n<p>Nous passons \u00e0 c\u00f4t\u00e9 de la Pierre Tombale du XIV\u00e8me si\u00e8cle, comportant des inscriptions en H\u00e9breu: il s&rsquo;agit du nom du d\u00e9funt \u00ab\u00a0rabbi Joseph fils de rabbi Nathana\u00ebl\u00a0\u00bb.<br>https:\/\/www.culture.gouv.fr\/regions\/Drac-Provence-Alpes-Cote-d-Azur\/Politique-et-actions-culturelles\/Conservation-regionale-des-monuments-historiques\/Patrimoine-juif-protege-au-titre-des-monuments-historiques-en-paca\/Hautes-Alpes-Serre-Pierre-tombale<\/p>\n\n\n\n<p>Nous rejoignons la cr\u00eate et son agr\u00e9able cheminement entre buis, ch\u00eanes et thym, avec une vue magnifique sur les sommets du D\u00e9voluy et alentours; dans la vall\u00e9e, la vaporeuse ouate r\u00e9siste, suivant le fil du Grand Bu\u00ebch\u2026<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"262\" src=\"https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_100042-584x262.jpg\" alt=\"\" class=\"wp-image-10738\" srcset=\"https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_100042-584x262.jpg 584w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_100042-300x135.jpg 300w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_100042-1536x690.jpg 1536w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_100042-2048x920.jpg 2048w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_100042-1200x539.jpg 1200w\" sizes=\"auto, (max-width: 584px) 85vw, 584px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"262\" src=\"https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_101017-584x262.jpg\" alt=\"\" class=\"wp-image-10739\" srcset=\"https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_101017-584x262.jpg 584w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_101017-300x135.jpg 300w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_101017-1536x690.jpg 1536w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_101017-2048x920.jpg 2048w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_101017-1200x539.jpg 1200w\" sizes=\"auto, (max-width: 584px) 85vw, 584px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"262\" src=\"https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_094453-584x262.jpg\" alt=\"\" class=\"wp-image-10741\" srcset=\"https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_094453-584x262.jpg 584w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_094453-300x135.jpg 300w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_094453-1536x690.jpg 1536w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_094453-2048x920.jpg 2048w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_094453-1200x539.jpg 1200w\" sizes=\"auto, (max-width: 584px) 85vw, 584px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p>Apr\u00e8s une petite pause au col de Saumane avant la partie de grimpette, nous atteignons la fontaine de l&rsquo;Ollagnier\u2026et apr\u00e8s la grimpette, le Carrefour qui am\u00e8ne \u00e0 droite vers la Bouisse, et que nous prenons \u00e0 gauche vers le Rocher de Jardanne.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"262\" src=\"https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_110221-584x262.jpg\" alt=\"\" class=\"wp-image-10742\" srcset=\"https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_110221-584x262.jpg 584w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_110221-300x135.jpg 300w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_110221-1536x690.jpg 1536w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_110221-2048x920.jpg 2048w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_110221-1200x539.jpg 1200w\" sizes=\"auto, (max-width: 584px) 85vw, 584px\" \/><\/figure>\n\n\n\n<p><br><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"262\" height=\"584\" src=\"https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_115813-262x584.jpg\" alt=\"\" class=\"wp-image-10743\" srcset=\"https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_115813-262x584.jpg 262w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_115813-135x300.jpg 135w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_115813-690x1536.jpg 690w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_115813-920x2048.jpg 920w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_115813-1200x2671.jpg 1200w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_115813-scaled.jpg 1150w\" sizes=\"auto, (max-width: 262px) 85vw, 262px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"262\" src=\"https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_120033-584x262.jpg\" alt=\"\" class=\"wp-image-10744\" srcset=\"https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_120033-584x262.jpg 584w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_120033-300x135.jpg 300w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_120033-1536x690.jpg 1536w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_120033-2048x920.jpg 2048w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_120033-1200x539.jpg 1200w\" sizes=\"auto, (max-width: 584px) 85vw, 584px\" \/><\/figure>\n\n\n\n<p>Cette fois c&rsquo;est lui qui est \u00e0 l&rsquo; honneur, \u00e9tant souvent snob\u00e9 pour la Bouisse, et le Bonnet Rouge !\u2026<br>Et il m\u00e9rite vraiment le temps qu&rsquo;on lui a consacr\u00e9, le temps du casse-cro\u00fbte sur une terrasse panoramique \u00e0 360\u00b0, tout le panel des sommets saupoudr\u00e9s du D\u00e9voluy, des \u00c9crins, un peu d&rsquo;Ubaye\u2026jusqu&rsquo;au Mont Ventoux\u2026<\/p>\n<\/div>\n<\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"262\" src=\"https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_122115-584x262.jpg\" alt=\"\" class=\"wp-image-10746\" srcset=\"https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_122115-584x262.jpg 584w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_122115-300x135.jpg 300w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_122115-1536x690.jpg 1536w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_122115-2048x920.jpg 2048w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_122115-1200x539.jpg 1200w\" sizes=\"auto, (max-width: 584px) 85vw, 584px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>Il nous fallait repartir \u00e0 regret\u2026et regagner le Col de Saumane avec prudence dans la descente. Nous bifurquons l\u00e0 vers Saumane, par le GR de Pays (Tour des Baronnies Proven\u00e7ales), sentier tr\u00e8s agr\u00e9able, jusqu&rsquo;\u00e0 rejoindre la grande ferme de Saumane et sa chapelle, nomm\u00e9e \u00e9galement Notre Dame des Anges\u2026 Quelques photos obligent !\u2026 Quelques compl\u00e9ments d&rsquo;informations sur ce lieu: https:\/\/www.cirkwi.com\/fr\/point-interet\/2789710-chapelle-notre-dame-de-saumane<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"262\" height=\"584\" src=\"https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_133514-262x584.jpg\" alt=\"\" class=\"wp-image-10747\" style=\"width:299px;height:auto\" srcset=\"https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_133514-262x584.jpg 262w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_133514-135x300.jpg 135w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_133514-690x1536.jpg 690w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_133514-920x2048.jpg 920w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_133514-1200x2671.jpg 1200w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_133514-scaled.jpg 1150w\" sizes=\"auto, (max-width: 262px) 85vw, 262px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"263\" height=\"584\" src=\"https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_140450-263x584.jpg\" alt=\"\" class=\"wp-image-10749\" style=\"width:299px;height:auto\" srcset=\"https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_140450-263x584.jpg 263w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_140450-135x300.jpg 135w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_140450-693x1536.jpg 693w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_140450-924x2048.jpg 924w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_140450-1200x2661.jpg 1200w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_140450-scaled.jpg 1155w\" sizes=\"auto, (max-width: 263px) 85vw, 263px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"263\" src=\"https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_140402-1-584x263.jpg\" alt=\"\" class=\"wp-image-10750\" srcset=\"https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_140402-1-584x263.jpg 584w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_140402-1-300x135.jpg 300w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_140402-1-1536x693.jpg 1536w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_140402-1-2048x924.jpg 2048w, https:\/\/sentiers05.fr\/wp-content\/uploads\/2024\/12\/IMG_20241201_140402-1-1200x541.jpg 1200w\" sizes=\"auto, (max-width: 584px) 85vw, 584px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>Puis nous continuons la piste jusqu&rsquo;\u00e0 rejoindre l&rsquo;\u00c9cole Communale de Serres, puis les voitures.<br>Une belle journ\u00e9e partag\u00e9e dans de beaux paysages, cl\u00f4tur\u00e9e autour d&rsquo;un verre convivial, au soleil, avant de revenir \u00e0 Gap et se s\u00e9parer jusqu&rsquo;\u00e0 la prochaine rando !\u2026<br>Merci \u00e0 vous et \u00e0 bient\u00f4t !<br><br>Annie Espitallier<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9n.750m-Dist.11km-Dur\u00e9e:5h-Diff.2+(portion de mont\u00e9e raide)6 participants Nous arrivons \u00e0 Serres pour 9h, accompagn\u00e9s d&rsquo;une nappe de brume givrante\u2026 Mais bien vite le soleil reprend ses marques. La mont\u00e9e commence doucement dans les ruelles de Serres jusqu&rsquo;\u00e0 la Chapelle de Bonsecour o\u00f9 une petite halte s&rsquo;impose: la vue sur la vall\u00e9e avec le voile justifie la plaque &hellip; <a href=\"https:\/\/sentiers05.fr\/index.php\/2024\/12\/01\/le-rocher-de-jardanne\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;Le Rocher de Jardanne&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-10732","post","type-post","status-publish","format-standard","hentry","category-randonnee-pedestre"],"_links":{"self":[{"href":"https:\/\/sentiers05.fr\/index.php\/wp-json\/wp\/v2\/posts\/10732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sentiers05.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sentiers05.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sentiers05.fr\/index.php\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/sentiers05.fr\/index.php\/wp-json\/wp\/v2\/comments?post=10732"}],"version-history":[{"count":8,"href":"https:\/\/sentiers05.fr\/index.php\/wp-json\/wp\/v2\/posts\/10732\/revisions"}],"predecessor-version":[{"id":10913,"href":"https:\/\/sentiers05.fr\/index.php\/wp-json\/wp\/v2\/posts\/10732\/revisions\/10913"}],"wp:attachment":[{"href":"https:\/\/sentiers05.fr\/index.php\/wp-json\/wp\/v2\/media?parent=10732"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sentiers05.fr\/index.php\/wp-json\/wp\/v2\/categories?post=10732"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sentiers05.fr\/index.php\/wp-json\/wp\/v2\/tags?post=10732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}